{"id":3713,"date":"2024-02-20T18:34:55","date_gmt":"2024-02-20T17:34:55","guid":{"rendered":"https:\/\/pop-co.fr\/index.php\/product\/blue-lock-bachira-meguru-figurine-17cm\/"},"modified":"2025-06-28T13:36:01","modified_gmt":"2025-06-28T11:36:01","slug":"blue-lock-bachira-meguru-figurine-17cm","status":"publish","type":"product","link":"https:\/\/pop-co.fr\/index.php\/product\/blue-lock-bachira-meguru-figurine-17cm\/","title":{"rendered":"BLUE LOCK &#8211; Bachira Meguru &#8211; Figurine 17cm"},"content":{"rendered":"<p>Pop Up Parade 17cm<br \/>\nComposition : PVC<\/p>\n<p>POP UP PARADE est une s\u00e9rie de figurines faciles \u00e0 collectionner, avec des prix abordables et des sorties rapides ! Chaque figurine mesure g\u00e9n\u00e9ralement entre 17 et 18 cm de haut et la s\u00e9rie comprend une vaste s\u00e9lection de personnages issus d&#8217;anime et de jeux populaires, et de nombreux autres seront bient\u00f4t ajout\u00e9s !<\/p>\n<p>Sculpteur : Mogwai<\/p>\n<p>Sp\u00e9cifications :<\/p>\n<p>Produits complets en plastique peint \u00e0 l&#8217;\u00e9chelle z\u00e9ro avec supports inclus. Environ 170 mm de hauteur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pop Up Parade 17cm Composition : PVC POP UP PARADE est une s\u00e9rie de figurines faciles \u00e0 collectionner, avec des prix abordables et des sorties rapides ! Chaque figurine mesure g\u00e9n\u00e9ralement entre 17 et 18 cm de haut et la s\u00e9rie comprend une vaste s\u00e9lection de personnages issus d&#8217;anime et de jeux populaires, et de [&hellip;]<\/p>\n","protected":false},"featured_media":161867,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[17,18],"product_tag":[],"aioseo_notices":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pop-co.fr\/index.php\/wp-json\/wp\/v2\/product\/3713"}],"collection":[{"href":"https:\/\/pop-co.fr\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pop-co.fr\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pop-co.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3713"}],"version-history":[{"count":0,"href":"https:\/\/pop-co.fr\/index.php\/wp-json\/wp\/v2\/product\/3713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pop-co.fr\/index.php\/wp-json\/wp\/v2\/media\/161867"}],"wp:attachment":[{"href":"https:\/\/pop-co.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3713"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pop-co.fr\/index.php\/wp-json\/wp\/v2\/product_cat?post=3713"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pop-co.fr\/index.php\/wp-json\/wp\/v2\/product_tag?post=3713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}